{"id":1784,"date":"2022-08-15T13:22:32","date_gmt":"2022-08-15T13:22:32","guid":{"rendered":"https:\/\/fiamacosmetici.netsons.org\/?post_type=product&#038;p=1784"},"modified":"2024-12-20T10:58:04","modified_gmt":"2024-12-20T10:58:04","slug":"gold-scrub","status":"publish","type":"product","link":"https:\/\/fiamacompany.com\/cosmesi\/product\/gold-scrub\/","title":{"rendered":"RENAISSANCE SCRUB"},"content":{"rendered":"<p><strong>Gold Scrub<\/strong> \u00e8 un innovativo trattamento cosmetico a base di oro, ideale per asportare le cellule<br \/>\nepidermiche superficiali, rimuovere tutte le impurit\u00e0 e donare nuova lucentezza<br \/>\ne splendore alla pelle.<br \/>\nGold Scrub contiene;<\/p>\n<ul>\n<li>Hexagold plus, oro ionico ed amminoacidi.<\/li>\n<li>Microsfere pluridimensionali di acido polilattico<\/li>\n<li>Acido jaluronic<\/li>\n<li>Gel di Aloe<\/li>\n<\/ul>\n<p>l&#8217;acido polilattitco (comunemente conosciuto come PLA) \u00e8 un efficace sistema ecosostenibile di pulizia e<br \/>\nrimozione degli strati superficiali della la pelle, caratterizzato da un&#8217;elevatissima dermocompatibilit\u00e0 ed<br \/>\necosostenibilit\u00e0) la sua granulometria pluridimensionale \u00e8 indicata per il trattamento del viso,<br \/>\nquesto dona al prodotto una totale azione esfoliante poich\u00e9 le microparticelle pi\u00f9 grandi agiscono sulle parti<br \/>\nche richiedono un&#8217;azione pi\u00f9 potente mentre quelle pi\u00f9 piccole levigano e completano il lavoro raggiungendo<br \/>\nun elevato dettaglio di pulizia e uniformit\u00e0.<\/p>\n<p>Gold Scrub non danneggia l&#8217;epidermide, non irrita, non causa infiammazioni da carica batterica.<br \/>\nGold Scrub \u00e8 amico dei mari, perch\u00e9 non inquina ed \u00e8 altamente e velocemente biodegradabile . 100% di<br \/>\nderivazione naturale (bio-fermentazione da fonti rinnovabili annualmente), ecocertificato (Cosmos).<br \/>\nInoltre Gold Scrub coontiene Hexagold Plus, (chimicamente composto da sei aminoacidi, con attivit\u00e0 simile<br \/>\na quello della tossina botulinica A.) Ideale per la sua capacit\u00e0 riducente la contrazione tonica dei muscoli<br \/>\nfacciali responsabili della comparsa delle rughe d&#8217;espressione. L\u2019associazione con acido ialuronico BT,<br \/>\nrende Gold Scrub, indicato per rallentare i processi della perdita di collagene e dell\u2019elastina, favorire la<br \/>\nrigenerazione del tessuto cutaneo, idratare la pelle e rimuovere le macchie, garantendo un risultato antiaging<br \/>\nduraturo nel tempo.<\/p>\n<p>&nbsp;<\/p>\n<h3>Modo d\u2019uso:<\/h3>\n<p>Su pelle ben detersa, aiutandosi con una spatolina o direttamente con la punta delle dita, applicare<br \/>\nun sottile strato di Gold Scrub sul viso, evitando il contorno occhi e l&#8217;attaccatura dei capelli. Lasciare in posa<br \/>\nper qualche minuto, successivamente con leggeri massaggi circolari asportare le cellule epiteliali insistendo<br \/>\ndove pi\u00f9 necessita. Rimuovere il prodotto con una spugnetta ed acqua tiepida.<\/p>\n<h3>Ingredients:<\/h3>\n<p><em>Aqua, Aloe Barbadensis Extract, Glycerin, Pla (Polylactic Acid), Xanthan Gum, Gold, Sodium Hyaluronate,<\/em><br \/>\n<em>Acetyl Hexaptapeptide-9, Maltodextrin, Silica, Mica, Phenoxyethanol, Hetylhexyl Glycerin, Parfum, Hexyl<\/em><br \/>\n<em>Cinnamal, Linalool, Geraniol, Citral, Sodium Dehydroacetate, Tetrasodium Glutamate Diacetate.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-1805\" src=\"http:\/\/www.fiamacosmesi.com\/wp-content\/uploads\/2022\/08\/firma-fiama-cosmesi.png\" alt=\"\" width=\"126\" height=\"67\" srcset=\"https:\/\/fiamacompany.com\/cosmesi\/wp-content\/uploads\/2022\/08\/firma-fiama-cosmesi.png 285w, https:\/\/fiamacompany.com\/cosmesi\/wp-content\/uploads\/2022\/08\/firma-fiama-cosmesi-90x48.png 90w, https:\/\/fiamacompany.com\/cosmesi\/wp-content\/uploads\/2022\/08\/firma-fiama-cosmesi-64x34.png 64w\" sizes=\"(max-width: 126px) 100vw, 126px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gold Scrub \u00e8 un innovativo trattamento cosmetico a base di oro, ideale per asportare le cellule epidermiche superficiali, rimuovere tutte le impurit\u00e0 e donare nuova lucentezza e splendore alla pelle. Gold Scrub contiene; Hexagold plus, oro ionico ed amminoacidi. Microsfere pluridimensionali di acido polilattico Acido jaluronic Gel di Aloe l&#8217;acido polilattitco (comunemente conosciuto come PLA)<\/p>\n<div class=\"klb-readmore entry-button\"><a class=\"button light alt medium\" href=\"https:\/\/fiamacompany.com\/cosmesi\/product\/gold-scrub\/\">Read More<\/a><\/div>\n","protected":false},"featured_media":2633,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[42],"product_tag":[86,87],"class_list":{"0":"post-1784","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-face","7":"product_tag-scrub","8":"product_tag-viso","10":"first","11":"outofstock","12":"sale","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/fiamacompany.com\/cosmesi\/wp-json\/wp\/v2\/product\/1784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fiamacompany.com\/cosmesi\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/fiamacompany.com\/cosmesi\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/fiamacompany.com\/cosmesi\/wp-json\/wp\/v2\/comments?post=1784"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fiamacompany.com\/cosmesi\/wp-json\/wp\/v2\/media\/2633"}],"wp:attachment":[{"href":"https:\/\/fiamacompany.com\/cosmesi\/wp-json\/wp\/v2\/media?parent=1784"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/fiamacompany.com\/cosmesi\/wp-json\/wp\/v2\/product_brand?post=1784"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/fiamacompany.com\/cosmesi\/wp-json\/wp\/v2\/product_cat?post=1784"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/fiamacompany.com\/cosmesi\/wp-json\/wp\/v2\/product_tag?post=1784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}